{"id":3395,"date":"2023-10-28T13:55:31","date_gmt":"2023-10-28T11:55:31","guid":{"rendered":"https:\/\/ineshock.de\/?p=3395"},"modified":"2023-10-28T14:26:49","modified_gmt":"2023-10-28T12:26:49","slug":"lyrismen-des-lichts-2007","status":"publish","type":"post","link":"https:\/\/ineshock.de\/en\/lyrismen-des-lichts-2007\/","title":{"rendered":"Lyrismen des Lichts, 2007"},"content":{"rendered":"<p><a href=\"https:\/\/ineshock.de\/wp-content\/uploads\/2023\/10\/katalog_hock_neuss_web.pdf\">Die Katalog PDF Lyrismen des Lichts<\/a><\/p>\n<p>ist zur gleichnamigen Ausstellung im Clemens-Sels-Museum, Neuss erschienen.<br \/>\nDie Bilder auf Leinwand sind f\u00fcr die besonderen architektonischen Gegebenheiten des Museums in 3 Farbreihen konzipiert worden.<\/p>\n<p><em><a href=\"https:\/\/ineshock.de\/die-schoene-seite-kunsthaus-wiesbaden-2007\/\" target=\"_blank\" rel=\"noopener\">Die sch\u00f6ne Seite<\/a>, eine &nbsp;Farbintervention im Kunsthaus Wiesbaden, <\/em>wird zusammen mit der 153 x 225 cm gro\u00dfen Bleistiftzeichnung Z 2007 -A und Polychromoszeichnungen dokumentiert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Katalog PDF Lyrismen des Lichts ist zur gleichnamigen Ausstellung im Clemens-Sels-Museum, Neuss erschienen. Die Bilder auf Leinwand sind f\u00fcr [&#8230;]<\/p>\n","protected":false},"author":2,"featured_media":3391,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-3395","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kataloge"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"en","enabled_languages":["de","en"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false}}},"_links":{"self":[{"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/posts\/3395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/comments?post=3395"}],"version-history":[{"count":7,"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/posts\/3395\/revisions"}],"predecessor-version":[{"id":3414,"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/posts\/3395\/revisions\/3414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/media\/3391"}],"wp:attachment":[{"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/media?parent=3395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/categories?post=3395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ineshock.de\/en\/wp-json\/wp\/v2\/tags?post=3395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}